{"id":3,"date":"2023-05-18T09:25:27","date_gmt":"2023-05-18T07:25:27","guid":{"rendered":"https:\/\/nashi.addlab.site\/?page_id=3"},"modified":"2023-08-25T15:05:56","modified_gmt":"2023-08-25T13:05:56","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/nashiargan.com\/global\/privacy-policy\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Chi siamo<\/h2><p><strong class=\"privacy-policy-tutorial\">Testo suggerito: <\/strong>L&#8217;indirizzo del nostro sito web \u00e8: https:\/\/nashiargan.com\/global.<\/p><h2 class=\"wp-block-heading\">Commenti<\/h2><p><strong class=\"privacy-policy-tutorial\">Testo suggerito: <\/strong>Quando i visitatori lasciano commenti sul sito, raccogliamo i dati mostrati nel modulo dei commenti oltre all&#8217;indirizzo IP del visitatore e la stringa dello user agent del browser per facilitare il rilevamento dello spam.<\/p><p>Una stringa anonimizzata creata a partire dal tuo indirizzo email (altrimenti detta hash) pu\u00f2 essere fornita al servizio Gravatar per vedere se lo stai usando. La privacy policy del servizio Gravatar \u00e8 disponibile qui: https:\/\/automattic.com\/privacy\/. Dopo l&#8217;approvazione del tuo commento, la tua immagine del profilo \u00e8 visibile al pubblico nel contesto del tuo commento.<\/p><h2 class=\"wp-block-heading\">Media<\/h2><p><strong class=\"privacy-policy-tutorial\">Testo suggerito: <\/strong>Se carichi immagini sul sito web, dovresti evitare di caricare immagini che includono i dati di posizione incorporati (EXIF GPS). I visitatori del sito web possono scaricare ed estrarre qualsiasi dato sulla posizione dalle immagini sul sito web.<\/p><h2 class=\"wp-block-heading\">Cookie<\/h2><p><strong class=\"privacy-policy-tutorial\">Testo suggerito: <\/strong>Se lasci un commento sul nostro sito, puoi scegliere di salvare il tuo nome, indirizzo email e sito web nei cookie. Sono usati per la tua comodit\u00e0 in modo che tu non debba inserire nuovamente i tuoi dati quando lasci un altro commento. Questi cookie dureranno per un anno.<\/p><p>Se visiti la pagina di login, verr\u00e0 impostato un cookie temporaneo per determinare se il tuo browser accetta i cookie. Questo cookie non contiene dati personali e viene eliminato quando chiudi il browser.<\/p><p>Quando effettui l&#8217;accesso, verranno impostati diversi cookie per salvare le tue informazioni di accesso e le tue opzioni di visualizzazione dello schermo. I cookie di accesso durano due giorni mentre i cookie per le opzioni dello schermo durano un anno. Se selezioni &quot;Ricordami&quot;, il tuo accesso persister\u00e0 per due settimane. Se esci dal tuo account, i cookie di accesso verranno rimossi.<\/p><p>Se modifichi o pubblichi un articolo, un cookie aggiuntivo verr\u00e0 salvato nel tuo browser. Questo cookie non include dati personali, ma indica semplicemente l&#8217;ID dell&#8217;articolo appena modificato. Scade dopo 1 giorno.<\/p><h2 class=\"wp-block-heading\">Contenuto incorporato da altri siti web<\/h2><p><strong class=\"privacy-policy-tutorial\">Testo suggerito: <\/strong>Gli articoli su questo sito possono includere contenuti incorporati (ad esempio video, immagini, articoli, ecc.). I contenuti incorporati da altri siti web si comportano esattamente allo stesso modo come se il visitatore avesse visitato l&#8217;altro sito web.<\/p><p>Questi siti web possono raccogliere dati su di te, usare cookie, integrare ulteriori tracciamenti di terze parti e monitorare l&#8217;interazione con essi, incluso il tracciamento della tua interazione con il contenuto incorporato se hai un account e sei connesso a quei siti web.<\/p><h2 class=\"wp-block-heading\">Con chi condividiamo i tuoi dati<\/h2><p><strong class=\"privacy-policy-tutorial\">Testo suggerito: <\/strong>Se richiedi una reimpostazione della password, il tuo indirizzo IP verr\u00e0 incluso nell&#8217;email di reimpostazione.<\/p><h2 class=\"wp-block-heading\">Per quanto tempo conserviamo i tuoi dati<\/h2><p><strong class=\"privacy-policy-tutorial\">Testo suggerito: <\/strong>Se lasci un commento, il commento e i relativi metadati vengono conservati a tempo indeterminato. \u00c8 cos\u00ec che possiamo riconoscere e approvare automaticamente eventuali commenti successivi invece di tenerli in una coda di moderazione.<\/p><p>Per gli utenti che si registrano sul nostro sito web (se presenti), memorizziamo anche le informazioni personali che forniscono nel loro profilo utente. Tutti gli utenti possono vedere, modificare o eliminare le loro informazioni personali in qualsiasi momento (eccetto il loro nome utente che non possono cambiare). Gli amministratori del sito web possono anche vedere e modificare queste informazioni.<\/p><h2 class=\"wp-block-heading\">Quali diritti hai sui tuoi dati<\/h2><p><strong class=\"privacy-policy-tutorial\">Testo suggerito: <\/strong>Se hai un account su questo sito, o hai lasciato commenti, puoi richiedere di ricevere un file esportato dal sito con i dati personali che abbiamo su di te, compresi i dati che ci hai fornito. Puoi anche richiedere che cancelliamo tutti i dati personali che ti riguardano. Questo non include i dati che siamo obbligati a conservare per scopi amministrativi, legali o di sicurezza.<\/p><h2 class=\"wp-block-heading\">Dove i tuoi dati sono inviati<\/h2><p><strong class=\"privacy-policy-tutorial\">Testo suggerito: <\/strong>I commenti dei visitatori possono essere controllati attraverso un servizio di rilevamento automatico dello spam.<\/p>","protected":false},"excerpt":{"rendered":"<p>Chi siamo Testo suggerito: L&#8217;indirizzo del nostro sito web \u00e8: https:\/\/nashiargan.com\/global. Commenti Testo suggerito: Quando i visitatori lasciano commenti sul sito, raccogliamo i dati mostrati nel modulo dei commenti oltre all&#8217;indirizzo IP del visitatore e la stringa dello user agent del browser per facilitare il rilevamento dello spam. Una stringa anonimizzata creata a partire dal [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Privacy Policy - Learn more - Nashi Argan<\/title>\n<meta name=\"description\" content=\"Protect your privacy. Find out how Nashi Argan handles and protects your personal data. Read our privacy policy to learn more.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nashiargan.com\/global\/privacy-policy\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy Policy - Learn more - Nashi Argan\" \/>\n<meta property=\"og:description\" content=\"Protect your privacy. Find out how Nashi Argan handles and protects your personal data. Read our privacy policy to learn more.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nashiargan.com\/global\/privacy-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"Nashi Argan\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NashiArganOfficial\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-25T13:05:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nashiargan.com\/wp-content\/uploads\/sites\/1\/2026\/04\/Senza-titolo-3-scaled-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nashiargan.com\/global\/privacy-policy\/\",\"url\":\"https:\/\/nashiargan.com\/global\/privacy-policy\/\",\"name\":\"Privacy Policy - Learn more - Nashi Argan\",\"isPartOf\":{\"@id\":\"https:\/\/nashiargan.com\/global\/#website\"},\"datePublished\":\"2023-05-18T07:25:27+00:00\",\"dateModified\":\"2023-08-25T13:05:56+00:00\",\"description\":\"Protect your privacy. Find out how Nashi Argan handles and protects your personal data. Read our privacy policy to learn more.\",\"breadcrumb\":{\"@id\":\"https:\/\/nashiargan.com\/global\/privacy-policy\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nashiargan.com\/global\/privacy-policy\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nashiargan.com\/global\/privacy-policy\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nashiargan.com\/global\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nashiargan.com\/global\/#website\",\"url\":\"https:\/\/nashiargan.com\/global\/\",\"name\":\"Nashi Argan - Global\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/nashiargan.com\/global\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nashiargan.com\/global\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/nashiargan.com\/global\/#organization\",\"name\":\"Nashi Argan - Global\",\"url\":\"https:\/\/nashiargan.com\/global\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/nashiargan.com\/global\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nashiargan.com\/wp-content\/uploads\/sites\/1\/2023\/05\/logo.jpg\",\"contentUrl\":\"https:\/\/nashiargan.com\/wp-content\/uploads\/sites\/1\/2023\/05\/logo.jpg\",\"width\":600,\"height\":600,\"caption\":\"Nashi Argan - Global\"},\"image\":{\"@id\":\"https:\/\/nashiargan.com\/global\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/NashiArganOfficial\",\"https:\/\/www.instagram.com\/nashiargan\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy Policy - Learn more - Nashi Argan","description":"Protect your privacy. Find out how Nashi Argan handles and protects your personal data. Read our privacy policy to learn more.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nashiargan.com\/global\/privacy-policy\/","og_locale":"en_US","og_type":"article","og_title":"Privacy Policy - Learn more - Nashi Argan","og_description":"Protect your privacy. Find out how Nashi Argan handles and protects your personal data. Read our privacy policy to learn more.","og_url":"https:\/\/nashiargan.com\/global\/privacy-policy\/","og_site_name":"Nashi Argan","article_publisher":"https:\/\/www.facebook.com\/NashiArganOfficial","article_modified_time":"2023-08-25T13:05:56+00:00","og_image":[{"width":2560,"height":854,"url":"https:\/\/nashiargan.com\/wp-content\/uploads\/sites\/1\/2026\/04\/Senza-titolo-3-scaled-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nashiargan.com\/global\/privacy-policy\/","url":"https:\/\/nashiargan.com\/global\/privacy-policy\/","name":"Privacy Policy - Learn more - Nashi Argan","isPartOf":{"@id":"https:\/\/nashiargan.com\/global\/#website"},"datePublished":"2023-05-18T07:25:27+00:00","dateModified":"2023-08-25T13:05:56+00:00","description":"Protect your privacy. Find out how Nashi Argan handles and protects your personal data. Read our privacy policy to learn more.","breadcrumb":{"@id":"https:\/\/nashiargan.com\/global\/privacy-policy\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nashiargan.com\/global\/privacy-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nashiargan.com\/global\/privacy-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nashiargan.com\/global\/"},{"@type":"ListItem","position":2,"name":"Privacy Policy"}]},{"@type":"WebSite","@id":"https:\/\/nashiargan.com\/global\/#website","url":"https:\/\/nashiargan.com\/global\/","name":"Nashi Argan - Global","description":"","publisher":{"@id":"https:\/\/nashiargan.com\/global\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nashiargan.com\/global\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/nashiargan.com\/global\/#organization","name":"Nashi Argan - Global","url":"https:\/\/nashiargan.com\/global\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nashiargan.com\/global\/#\/schema\/logo\/image\/","url":"https:\/\/nashiargan.com\/wp-content\/uploads\/sites\/1\/2023\/05\/logo.jpg","contentUrl":"https:\/\/nashiargan.com\/wp-content\/uploads\/sites\/1\/2023\/05\/logo.jpg","width":600,"height":600,"caption":"Nashi Argan - Global"},"image":{"@id":"https:\/\/nashiargan.com\/global\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NashiArganOfficial","https:\/\/www.instagram.com\/nashiargan\/"]}]}},"_links":{"self":[{"href":"https:\/\/nashiargan.com\/global\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nashiargan.com\/global\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nashiargan.com\/global\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nashiargan.com\/global\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nashiargan.com\/global\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":3,"href":"https:\/\/nashiargan.com\/global\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":9256,"href":"https:\/\/nashiargan.com\/global\/wp-json\/wp\/v2\/pages\/3\/revisions\/9256"}],"wp:attachment":[{"href":"https:\/\/nashiargan.com\/global\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}